{"id":11,"count":2,"description":"","link":"https:\/\/www.coanfiliving.com\/actualidad\/category\/inmobiliario\/","name":"Inmobiliario","slug":"inmobiliario","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.coanfiliving.com\/actualidad\/wp-json\/wp\/v2\/categories\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coanfiliving.com\/actualidad\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.coanfiliving.com\/actualidad\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.coanfiliving.com\/actualidad\/wp-json\/wp\/v2\/posts?categories=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}